{"id":405,"count":36,"description":"","link":"https:\/\/milk-cheese.com.ua\/en\/milk-products\/cheese-butter\/hard-cheeses-mozzarella-cheddar-cheese\/","name":"Hard cheeses, mozzarella, cheddar cheese","slug":"hard-cheeses-mozzarella-cheddar-cheese","taxonomy":"product_cat","parent":420,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Hard cheeses, mozzarella, cheddar cheese \u0410\u0440\u0445\u0456\u0432\u0438 - \u041b\u0456\u043a\u043e - \u0422\u043e\u0440\u0433\u043e\u0432\u0438\u0439 \u0434\u0456\u043c<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/milk-cheese.com.ua\/en\/milk-products\/cheese-butter\/hard-cheeses-mozzarella-cheddar-cheese\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hard cheeses, mozzarella, cheddar cheese \u0410\u0440\u0445\u0456\u0432\u0438 - \u041b\u0456\u043a\u043e - \u0422\u043e\u0440\u0433\u043e\u0432\u0438\u0439 \u0434\u0456\u043c\" \/>\n<meta property=\"og:url\" content=\"https:\/\/milk-cheese.com.ua\/en\/milk-products\/cheese-butter\/hard-cheeses-mozzarella-cheddar-cheese\/\" \/>\n<meta property=\"og:site_name\" content=\"\u041b\u0456\u043a\u043e - \u0422\u043e\u0440\u0433\u043e\u0432\u0438\u0439 \u0434\u0456\u043c\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/milk-cheese.com.ua\/en\/milk-products\/cheese-butter\/hard-cheeses-mozzarella-cheddar-cheese\/\",\"url\":\"https:\/\/milk-cheese.com.ua\/en\/milk-products\/cheese-butter\/hard-cheeses-mozzarella-cheddar-cheese\/\",\"name\":\"Hard cheeses, mozzarella, cheddar cheese \u0410\u0440\u0445\u0456\u0432\u0438 - \u041b\u0456\u043a\u043e - \u0422\u043e\u0440\u0433\u043e\u0432\u0438\u0439 \u0434\u0456\u043c\",\"isPartOf\":{\"@id\":\"https:\/\/milk-cheese.com.ua\/en\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/milk-cheese.com.ua\/en\/milk-products\/cheese-butter\/hard-cheeses-mozzarella-cheddar-cheese\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/milk-cheese.com.ua\/en\/milk-products\/cheese-butter\/hard-cheeses-mozzarella-cheddar-cheese\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u0413\u043e\u043b\u043e\u0432\u043d\u0430\",\"item\":\"https:\/\/milk-cheese.com.ua\/en\/home\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Milk products\",\"item\":\"https:\/\/milk-cheese.com.ua\/en\/milk-products\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Cheese, butter\",\"item\":\"https:\/\/milk-cheese.com.ua\/en\/milk-products\/cheese-butter\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Hard cheeses, mozzarella, cheddar cheese\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/milk-cheese.com.ua\/en\/#website\",\"url\":\"https:\/\/milk-cheese.com.ua\/en\/\",\"name\":\"\u041b\u0456\u043a\u043e - \u0422\u043e\u0440\u0433\u043e\u0432\u0438\u0439 \u0434\u0456\u043c\",\"description\":\"\u041f\u0440\u043e\u0434\u0443\u043a\u0442\u0438 \u0445\u0430\u0440\u0447\u0443\u0432\u0430\u043d\u043d\u044f \u0454\u0432\u0440\u043e\u043f\u0435\u0439\u0441\u044c\u043a\u043e\u0433\u043e \u0432\u0438\u0440\u043e\u0431\u043d\u0438\u0446\u0442\u0432\u0430\",\"publisher\":{\"@id\":\"https:\/\/milk-cheese.com.ua\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/milk-cheese.com.ua\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/milk-cheese.com.ua\/en\/#organization\",\"name\":\"\u041b\u0456\u043a\u043e - \u0422\u043e\u0440\u0433\u043e\u0432\u0438\u0439 \u0434\u0456\u043c\",\"url\":\"https:\/\/milk-cheese.com.ua\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/milk-cheese.com.ua\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/milk-cheese.com.ua\/wp-content\/uploads\/2023\/06\/liko.svg\",\"contentUrl\":\"https:\/\/milk-cheese.com.ua\/wp-content\/uploads\/2023\/06\/liko.svg\",\"caption\":\"\u041b\u0456\u043a\u043e - \u0422\u043e\u0440\u0433\u043e\u0432\u0438\u0439 \u0434\u0456\u043c\"},\"image\":{\"@id\":\"https:\/\/milk-cheese.com.ua\/en\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hard cheeses, mozzarella, cheddar cheese \u0410\u0440\u0445\u0456\u0432\u0438 - \u041b\u0456\u043a\u043e - \u0422\u043e\u0440\u0433\u043e\u0432\u0438\u0439 \u0434\u0456\u043c","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/milk-cheese.com.ua\/en\/milk-products\/cheese-butter\/hard-cheeses-mozzarella-cheddar-cheese\/","og_locale":"en_US","og_type":"article","og_title":"Hard cheeses, mozzarella, cheddar cheese \u0410\u0440\u0445\u0456\u0432\u0438 - \u041b\u0456\u043a\u043e - \u0422\u043e\u0440\u0433\u043e\u0432\u0438\u0439 \u0434\u0456\u043c","og_url":"https:\/\/milk-cheese.com.ua\/en\/milk-products\/cheese-butter\/hard-cheeses-mozzarella-cheddar-cheese\/","og_site_name":"\u041b\u0456\u043a\u043e - \u0422\u043e\u0440\u0433\u043e\u0432\u0438\u0439 \u0434\u0456\u043c","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/milk-cheese.com.ua\/en\/milk-products\/cheese-butter\/hard-cheeses-mozzarella-cheddar-cheese\/","url":"https:\/\/milk-cheese.com.ua\/en\/milk-products\/cheese-butter\/hard-cheeses-mozzarella-cheddar-cheese\/","name":"Hard cheeses, mozzarella, cheddar cheese \u0410\u0440\u0445\u0456\u0432\u0438 - \u041b\u0456\u043a\u043e - \u0422\u043e\u0440\u0433\u043e\u0432\u0438\u0439 \u0434\u0456\u043c","isPartOf":{"@id":"https:\/\/milk-cheese.com.ua\/en\/#website"},"breadcrumb":{"@id":"https:\/\/milk-cheese.com.ua\/en\/milk-products\/cheese-butter\/hard-cheeses-mozzarella-cheddar-cheese\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/milk-cheese.com.ua\/en\/milk-products\/cheese-butter\/hard-cheeses-mozzarella-cheddar-cheese\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u0413\u043e\u043b\u043e\u0432\u043d\u0430","item":"https:\/\/milk-cheese.com.ua\/en\/home\/"},{"@type":"ListItem","position":2,"name":"Milk products","item":"https:\/\/milk-cheese.com.ua\/en\/milk-products\/"},{"@type":"ListItem","position":3,"name":"Cheese, butter","item":"https:\/\/milk-cheese.com.ua\/en\/milk-products\/cheese-butter\/"},{"@type":"ListItem","position":4,"name":"Hard cheeses, mozzarella, cheddar cheese"}]},{"@type":"WebSite","@id":"https:\/\/milk-cheese.com.ua\/en\/#website","url":"https:\/\/milk-cheese.com.ua\/en\/","name":"\u041b\u0456\u043a\u043e - \u0422\u043e\u0440\u0433\u043e\u0432\u0438\u0439 \u0434\u0456\u043c","description":"\u041f\u0440\u043e\u0434\u0443\u043a\u0442\u0438 \u0445\u0430\u0440\u0447\u0443\u0432\u0430\u043d\u043d\u044f \u0454\u0432\u0440\u043e\u043f\u0435\u0439\u0441\u044c\u043a\u043e\u0433\u043e \u0432\u0438\u0440\u043e\u0431\u043d\u0438\u0446\u0442\u0432\u0430","publisher":{"@id":"https:\/\/milk-cheese.com.ua\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/milk-cheese.com.ua\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/milk-cheese.com.ua\/en\/#organization","name":"\u041b\u0456\u043a\u043e - \u0422\u043e\u0440\u0433\u043e\u0432\u0438\u0439 \u0434\u0456\u043c","url":"https:\/\/milk-cheese.com.ua\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/milk-cheese.com.ua\/en\/#\/schema\/logo\/image\/","url":"https:\/\/milk-cheese.com.ua\/wp-content\/uploads\/2023\/06\/liko.svg","contentUrl":"https:\/\/milk-cheese.com.ua\/wp-content\/uploads\/2023\/06\/liko.svg","caption":"\u041b\u0456\u043a\u043e - \u0422\u043e\u0440\u0433\u043e\u0432\u0438\u0439 \u0434\u0456\u043c"},"image":{"@id":"https:\/\/milk-cheese.com.ua\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/milk-cheese.com.ua\/en\/wp-json\/wp\/v2\/product_cat\/405","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/milk-cheese.com.ua\/en\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/milk-cheese.com.ua\/en\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/milk-cheese.com.ua\/en\/wp-json\/wp\/v2\/product_cat\/420"}],"wp:post_type":[{"href":"https:\/\/milk-cheese.com.ua\/en\/wp-json\/wp\/v2\/product?product_cat=405"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}